{"id":437,"date":"2011-06-19T18:46:58","date_gmt":"2011-06-19T17:46:58","guid":{"rendered":"http:\/\/www.rhbnm.it\/?p=437"},"modified":"2016-01-30T11:56:28","modified_gmt":"2016-01-30T10:56:28","slug":"kk-7355","status":"publish","type":"post","link":"http:\/\/www.rhbnm.it\/index.php\/modelli\/carri-merci\/kk-7355\/","title":{"rendered":"Kk 7355"},"content":{"rendered":"<p>Modello\u00a0<strong><a title=\"AB-Modell\" href=\"http:\/\/www.rhbnm.it\/index.php\/indirizzi\/vendita\/ab-modell\/\">AB-Modell<\/a><\/strong> art. Nm-012.2<\/p>\n<p>Epoca IV.<\/p>\n<p><a title=\"Kk 7355\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-1.jpg\" rel=\"lightbox[kk-7355]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-444\" title=\"Kk 7355\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-1-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-1-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-1-300x200.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-1.jpg 1974w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Dopo anni di uso intensivo, i carri a sponde basse in legno originari degli anni 1911 e 1913, erano molto logorati e usurati.<\/p>\n<p>Dato che le necessit\u00e0 di trasporto con i carri aperti erano immutate, ci furono una serie di ristrutturazioni.<\/p>\n<p>Queste portarono negli anni sessanta ad una serie di vagoni destinati al trasporto della ghiaia in contenitori e le sponde in legno furono eliminate.<\/p>\n<p><a title=\"Kk 7355\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-2.jpg\" rel=\"lightbox[kk-7355]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-445\" title=\"Kk 7355\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-2-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-2-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-2-300x199.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-2.jpg 1781w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Dopo l&#8217;acquisto di moderni carri per il trasporto della ghiaia, per soddisfare la crescente domanda di carri per il trasporto del legname, nel 1989 i contenitori furono rimossi e montati degli stanti fissi.<\/p>\n<p>Nonostante molte variet\u00e0 di ulteriori carri a stanti a quattro assi, la Ferrovia Retica mantenne inalterati i piccoli due assi nei servizi merci.<\/p>\n<p><a title=\"Kk 7355\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-3.jpg\" rel=\"lightbox[kk-7355]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-446\" title=\"Kk 7355\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-3-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-3-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-3-300x199.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-3.jpg 1480w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Gli esemplari Kk 7351 &#8211; 7364 furono attrezzati nel 1963 per il trasporto della ghiaia e nel 1989 muniti di stanti.<\/p>\n<p>Gli stanti erano bloccati dritti e le pareti frontali inserite.<\/p>\n<p>I Kk-w 7346, 7350 e 7355 entrarono in servizio nel 1913 come MI, nel 1963 equipaggiati con due contenitori per la ghiaia e nel 1989 nel loro aspetto attuale dall&#8217;inizio degli anni 90, senza bordo, con ulteriori anelli di fissaggio e i aggiunta una vecchia ringhiera squadrata.<\/p>\n<p><a title=\"Kk 7355\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-4.jpg\" rel=\"lightbox[kk-7355]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-447\" title=\"Kk 7355\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-4-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-4-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-4-300x200.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2011\/06\/kk7355-4.jpg 1434w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Il veicolo \u00e8 realizzato in scala 1:160, costruito completamente in ottone e metallo bianco. Ruote dettagliate e brunite per un perfetto funzionamento. Equipaggiato con ganci Micro-Trains-Line per Nm.<\/p>\n<p><span style=\"color: #888888;\">Matricola modello: 39<\/span><\/p>\n<div class=\"post-date author-description\">Ultimo aggiornamento: 30-01-2016<\/div>","protected":false},"excerpt":{"rendered":"<p>Modello\u00a0AB-Modell art. Nm-012.2 Epoca IV. Dopo anni di uso intensivo, i carri a sponde basse in legno originari degli anni 1911 e 1913, erano molto logorati e usurati. Dato che le necessit\u00e0 di trasporto con i carri aperti erano immutate, ci furono una serie di ristrutturazioni. Queste portarono negli anni sessanta ad una serie di &hellip; <a href=\"http:\/\/www.rhbnm.it\/index.php\/modelli\/carri-merci\/kk-7355\/\" class=\"more-link\">Continua la lettura di <span class=\"screen-reader-text\">Kk 7355<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts\/437"}],"collection":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/comments?post=437"}],"version-history":[{"count":9,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts\/437\/revisions"}],"predecessor-version":[{"id":753,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts\/437\/revisions\/753"}],"wp:attachment":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/media?parent=437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/categories?post=437"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/tags?post=437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}