{"id":781,"date":"2016-04-11T12:25:05","date_gmt":"2016-04-11T11:25:05","guid":{"rendered":"http:\/\/www.rhbnm.it\/?p=781"},"modified":"2016-04-11T12:25:05","modified_gmt":"2016-04-11T11:25:05","slug":"lb-v-7869","status":"publish","type":"post","link":"http:\/\/www.rhbnm.it\/index.php\/modelli\/carri-merci\/lb-v-7869\/","title":{"rendered":"Lb-v 7869"},"content":{"rendered":"<p>Modello <a href=\"http:\/\/www.rhbnm.it\/index.php\/indirizzi\/produzione\/schlosser\/\">Schlosser<\/a><\/p>\n<p>Epoca V-VI.<\/p>\n<p><a title=\"Lb-v 7869\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-1.jpg\" rel=\"lightbox[Lb-v 7869]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-782\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-1-400x266.jpg\" alt=\"Lb-v 7869\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-1-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-1-300x199.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-1-768x510.jpg 768w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-1.jpg 1974w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Per evitare i continui e costosi trasbordi di merci, per es. da scartamento normale a quello ridotto, e per evitare la distribuzione delle stesse sui singoli autocarri, la Ferrovia retica costru\u00ec, partendo da vagoni merci coperti della serie Gb 5000-5100, una serie di pianali del gruppo Lb-v 78XX. Il telaio dei carri \u00e8 stato modificato in modo che trovassero posto gli agganci per container e casse mobili.<\/p>\n<p><a title=\"Lb-v 7869\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-2-1.jpg\" rel=\"lightbox[Lb-v 7869]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-785\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-2-1-400x266.jpg\" alt=\"Lb-v 7869\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-2-1-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-2-1-300x199.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-2-1-768x511.jpg 768w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-2-1.jpg 1474w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Nello scalo merci di Landquart pu\u00f2 essere eseguito lo scambio dei container da scartamento normale a quello ridotto, visto che i carri per il trasporto dei vagoni a scartamento normale non possono essere utilizzati su tutta la rete.\u00a0Anche le casse mobili possono essere spostate da e sugli autocarri, tramite le gru presenti nei terminal merci della RhB.\u00a0In questo modo la posta o anche alimentari di grandi catene di distribuzione giungono dalle rotaie vicino al consumatore finale. Visto che la maggior parte delle cassemobili dispone di un portellone laterale, queste possono essere scaricate anche in stazioni in cui non sono presenti gru, come normali vagoni merci.<\/p>\n<p><a title=\"Lb-v 7869\" href=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-3.jpg\" rel=\"lightbox[Lb-v 7869]\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-786\" src=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-3-400x266.jpg\" alt=\"Lb-v 7869\" width=\"400\" height=\"266\" srcset=\"http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-3-400x266.jpg 400w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-3-300x199.jpg 300w, http:\/\/www.rhbnm.it\/wp-content\/uploads\/2016\/04\/lbv7869-3-768x511.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>I vagoni della serie Lb-v si trovano non solo in composizione a treni merci, ma spesso anche in treni ad espressi Coira &#8211; St. Moritz, dove, se necessario, possono essere manovrati nelle stazioni intermedie.<\/p>\n<p>Il veicolo \u00e8 realizzato in scala 1:160 a scartamento ridotto, in ottone e metallo bianco ed \u00e8 equipaggiato con ganci Micro-Trains-Line per Nm.<\/p>\n<div class=\"post-date author-description\">Ultimo aggiornamento: 11-04-2016<\/div>","protected":false},"excerpt":{"rendered":"<p>Modello Schlosser Epoca V-VI. Per evitare i continui e costosi trasbordi di merci, per es. da scartamento normale a quello ridotto, e per evitare la distribuzione delle stesse sui singoli autocarri, la Ferrovia retica costru\u00ec, partendo da vagoni merci coperti della serie Gb 5000-5100, una serie di pianali del gruppo Lb-v 78XX. Il telaio dei &hellip; <a href=\"http:\/\/www.rhbnm.it\/index.php\/modelli\/carri-merci\/lb-v-7869\/\" class=\"more-link\">Continua la lettura di <span class=\"screen-reader-text\">Lb-v 7869<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts\/781"}],"collection":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/comments?post=781"}],"version-history":[{"count":5,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts\/781\/revisions"}],"predecessor-version":[{"id":795,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/posts\/781\/revisions\/795"}],"wp:attachment":[{"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/media?parent=781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/categories?post=781"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhbnm.it\/index.php\/wp-json\/wp\/v2\/tags?post=781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}